{"id":1412,"date":"2024-04-11T15:19:07","date_gmt":"2024-04-11T12:19:07","guid":{"rendered":"http:\/\/jnats.eu\/?post_type=product&#038;p=1412"},"modified":"2025-03-04T09:11:01","modified_gmt":"2025-03-04T07:11:01","slug":"okudo-shiro-suita-piedra-de-afilar-natural-japonesa","status":"publish","type":"product","link":"https:\/\/jnats.eu\/es\/produktas\/okudo-shiro-suita-japoniskas-naturalus-galandimo-akmuo\/","title":{"rendered":"Piedra de afilar natural japonesa Okudo Shiro Suita"},"content":{"rendered":"<ul class=\"wp-block-list\">\n<li>Adecuado para el acabado de navajas, cuchillos, tijeras, carpinter\u00eda y otras herramientas.<\/li>\n\n\n\n<li>Dimensiones: 203x74x42mm<\/li>\n\n\n\n<li>Peso: 1620 gramos<\/li>\n\n\n\n<li>Dureza: Nivel 4,5<\/li>\n\n\n\n<li>Se caracteriza por una velocidad de trabajo media y uniformidad. La aceleraci\u00f3n se puede lograr con la ayuda de una brazada de espalda o frotando con una placa de diamante en bruto. Pule a un espejo.<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p><!-- wp:list --><\/p>\n<ul><!-- wp:list-item --><\/p>\n<li>Adecuado para el acabado de navajas, cuchillos, tijeras, carpinter\u00eda y otras herramientas.<\/li>\n<p><!-- \/wp:list-item --><\/p>\n<p><!-- wp:list-item --><\/p>\n<li>Dimensiones: 203x74x42mm<\/li>\n<p><!-- \/wp:list-item --><\/p>\n<p><!-- wp:list-item --><\/p>\n<li>Peso: 1620 gramos<\/li>\n<p><!-- \/wp:list-item --><\/p>\n<p><!-- wp:list-item --><\/p>\n<li>Dureza: Nivel 4,5<\/li>\n<p><!-- \/wp:list-item --><\/p>\n<p><!-- wp:list-item --><\/p>\n<li>Se caracteriza por una velocidad de trabajo media y uniformidad. La aceleraci\u00f3n se puede lograr con la ayuda de una brazada de espalda o frotando con una placa de diamante en bruto. Pule a un espejo.<\/li>\n<p><!-- \/wp:list-item --><\/ul>\n<p><!-- \/wp:list --><\/p>","protected":false},"featured_media":1416,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[22],"product_tag":[142,87,50],"class_list":["post-1412","product","type-product","status-publish","has-post-thumbnail","product_cat-jnats","product_tag-okudo","product_tag-shiro","product_tag-suita","first","outofstock","sale","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/jnats.eu\/es\/wp-json\/wp\/v2\/product\/1412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jnats.eu\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/jnats.eu\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/jnats.eu\/es\/wp-json\/wp\/v2\/comments?post=1412"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jnats.eu\/es\/wp-json\/wp\/v2\/media\/1416"}],"wp:attachment":[{"href":"https:\/\/jnats.eu\/es\/wp-json\/wp\/v2\/media?parent=1412"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/jnats.eu\/es\/wp-json\/wp\/v2\/product_brand?post=1412"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/jnats.eu\/es\/wp-json\/wp\/v2\/product_cat?post=1412"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/jnats.eu\/es\/wp-json\/wp\/v2\/product_tag?post=1412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}